{"id":5603,"date":"2018-04-12T09:30:19","date_gmt":"2018-04-12T07:30:19","guid":{"rendered":"https:\/\/www.casedilussoeuropa.com\/info\/?p=5603"},"modified":"2019-07-31T11:02:20","modified_gmt":"2019-07-31T09:02:20","slug":"villae-13-lusso-interior-design-tecnologia","status":"publish","type":"post","link":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/","title":{"rendered":"Villae 13: lusso, interior design e tecnologia"},"content":{"rendered":"<p>Lusso, interior design e tecnologia sono i tre concetti su cui si basa Villae 13. Il design degli interni si converte nel filo conduttore dell\u2019ultima edizione di Villae International, rivista pubblicata da EREN con contenuti esclusivi. Inoltre troverete un campionario delle <strong>propriet\u00e0 pi\u00f9 lussuose d\u2019Europa<\/strong>. Quest\u2019ultime sono state estratte dal portfolio di ciascuno dei soci della rete immobiliare europea.<\/p>\n<p>Gi\u00e0 dalla sua copertina possiamo intuire che l\u2019interior design \u00e8 il vero protagonista di Villae 13. In prima pagina appare un elegante <strong>loft imperiale<\/strong> nel cuore della citt\u00e0 di Vienna che combina una decorazione raffinata di interni e graziosi elementi architettonici. Questi ultimi ereditati dall\u2019edificio storico in cui si trova.<\/p>\n<h2>Il top in termini di lusso, interior design e tecnologia<\/h2>\n<p>Alcuni dei contenuti che trover\u00e0 nella rivista sono: <strong>nuove tendenze di decorazione<\/strong>, come l\u2019uso di tessuti che serve a dare un tocco glamour e creare uno spazio accogliente. Inoltre si incontrano lussuose residenze di campagna e le propriet\u00e0 pi\u00f9 esclusive d\u2019Europa. Ma la concezione di spazi non si limita solo al settore residenziale, bens\u00ec, si estende fino ad aerei di lusso e bar situati in citt\u00e0 come Mumbai, Xanthi o Singapore, dei quali la rivista ci offre una piccola selezione.<\/p>\n<p>Al suo interno la aspettano anche altri temi esclusivi come un articolo sul visionario <strong>Elon Musk<\/strong>, direttore e cofondatore di Tesla Motors e Solar City, PayPal, SpaceX e OpenAl (tra altre imprese di punta); il mondo dell\u2019oro, nuovi <em>gadget<\/em> e citt\u00e0 intelligenti.<\/p>\n<p>Dall\u2019altra parte e come in ogni edizione, anche Villae 13 fa una revisione delle conferenze annuali di EREN che l\u2019anno scorso ebbero luogo in Austria e Francia. Inoltre in questa occasione EREN ha il piacere di presentare un nuovo membro, <strong>Comptoir Immobilier<\/strong>. Si tratta di una agenzia immobiliare leader del mercato immobiliare a Ginevra, Svizzera.<\/p>\n<p>Se desidera pu\u00f2 leggere Villae 13, cos\u00ec come le edizioni precedenti della rivista <em>Villae International <\/em>attraverso questo <a href=\"https:\/\/www.europeanrealestate.org\/it\/rivista-villae-international\/13\" target=\"_blank\" rel=\"noopener noreferrer\">link<\/a>.<\/p>\n<div id='gallery-1' class='gallery galleryid-5603 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1-1024x685.jpg\" class=\"attachment-large size-large\" alt=\"Residenze di campagna in Europa\" srcset=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1.jpg 1024w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1-300x201.jpg 300w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1-768x514.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"523\" src=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2-1024x686.jpg\" class=\"attachment-large size-large\" alt=\"Aerei di lusso\" srcset=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2.jpg 1024w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2-300x201.jpg 300w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2-768x515.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3-1024x685.jpg\" class=\"attachment-large size-large\" alt=\"Bar esclusivi\" srcset=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3.jpg 1024w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3-300x201.jpg 300w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3-768x514.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>EREN pubblica la tredicesima edizione di Villae International, rivista con contenuti esclusivi e un campionario delle propriet\u00e0 pi\u00f9 lussuose d\u2019Europa.<\/p>\n","protected":false},"author":1,"featured_media":9310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1085],"tags":[5219,5149,5165,5175,5139,5185],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lusso, interior design e tecnologia nella rivista Villae 13 | EREN<\/title>\n<meta name=\"description\" content=\"Rivista Villae 13: ultime tendenze nel campo del lusso, dell&#039;interior design e della tecnologia, oltre alle propriet\u00e0 pi\u00f9 lussuose d&#039;Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lusso, interior design e tecnologia nella rivista Villae 13 | EREN\" \/>\n<meta property=\"og:description\" content=\"Rivista Villae 13: ultime tendenze nel campo del lusso, dell&#039;interior design e della tecnologia, oltre alle propriet\u00e0 pi\u00f9 lussuose d&#039;Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"EREN\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-12T07:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-31T09:02:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EREN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EREN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\"},\"author\":{\"name\":\"EREN\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d\"},\"headline\":\"Villae 13: lusso, interior design e tecnologia\",\"datePublished\":\"2018-04-12T07:30:19+00:00\",\"dateModified\":\"2019-07-31T09:02:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"keywords\":[\"EREN\",\"Interior design\",\"Lusso\",\"Propriet\u00e0 di lusso in Europa\",\"Rivista Villae International\",\"Tecnologie\"],\"articleSection\":[\"Rivista Villae International\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\",\"name\":\"Lusso, interior design e tecnologia nella rivista Villae 13 | EREN\",\"isPartOf\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"datePublished\":\"2018-04-12T07:30:19+00:00\",\"dateModified\":\"2019-07-31T09:02:20+00:00\",\"description\":\"Rivista Villae 13: ultime tendenze nel campo del lusso, dell'interior design e della tecnologia, oltre alle propriet\u00e0 pi\u00f9 lussuose d'Europa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"contentUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"width\":1024,\"height\":685,\"caption\":\"Lusso, interior design e tecnologia nella rivista Villae 13\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.europeanrealestate.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villae 13: lusso, interior design e tecnologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#website\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/\",\"name\":\"EREN\",\"description\":\"European Real Estate Network\",\"publisher\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.europeanrealestate.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#organization\",\"name\":\"EREN\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg\",\"contentUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg\",\"width\":184,\"height\":14,\"caption\":\"EREN\"},\"image\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d\",\"name\":\"EREN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g\",\"caption\":\"EREN\"},\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/author\/eren\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lusso, interior design e tecnologia nella rivista Villae 13 | EREN","description":"Rivista Villae 13: ultime tendenze nel campo del lusso, dell'interior design e della tecnologia, oltre alle propriet\u00e0 pi\u00f9 lussuose d'Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/","og_locale":"es_ES","og_type":"article","og_title":"Lusso, interior design e tecnologia nella rivista Villae 13 | EREN","og_description":"Rivista Villae 13: ultime tendenze nel campo del lusso, dell'interior design e della tecnologia, oltre alle propriet\u00e0 pi\u00f9 lussuose d'Europa.","og_url":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/","og_site_name":"EREN","article_published_time":"2018-04-12T07:30:19+00:00","article_modified_time":"2019-07-31T09:02:20+00:00","og_image":[{"width":1024,"height":685,"url":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","type":"image\/jpeg"}],"author":"EREN","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EREN","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#article","isPartOf":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/"},"author":{"name":"EREN","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d"},"headline":"Villae 13: lusso, interior design e tecnologia","datePublished":"2018-04-12T07:30:19+00:00","dateModified":"2019-07-31T09:02:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/"},"wordCount":331,"publisher":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#organization"},"image":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","keywords":["EREN","Interior design","Lusso","Propriet\u00e0 di lusso in Europa","Rivista Villae International","Tecnologie"],"articleSection":["Rivista Villae International"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/","url":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/","name":"Lusso, interior design e tecnologia nella rivista Villae 13 | EREN","isPartOf":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage"},"image":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","datePublished":"2018-04-12T07:30:19+00:00","dateModified":"2019-07-31T09:02:20+00:00","description":"Rivista Villae 13: ultime tendenze nel campo del lusso, dell'interior design e della tecnologia, oltre alle propriet\u00e0 pi\u00f9 lussuose d'Europa.","breadcrumb":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#primaryimage","url":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","contentUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","width":1024,"height":685,"caption":"Lusso, interior design e tecnologia nella rivista Villae 13"},{"@type":"BreadcrumbList","@id":"https:\/\/www.europeanrealestate.org\/blog\/it\/villae-13-lusso-interior-design-tecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.europeanrealestate.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Villae 13: lusso, interior design e tecnologia"}]},{"@type":"WebSite","@id":"https:\/\/www.europeanrealestate.org\/blog\/#website","url":"https:\/\/www.europeanrealestate.org\/blog\/","name":"EREN","description":"European Real Estate Network","publisher":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.europeanrealestate.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.europeanrealestate.org\/blog\/#organization","name":"EREN","url":"https:\/\/www.europeanrealestate.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg","contentUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg","width":184,"height":14,"caption":"EREN"},"image":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d","name":"EREN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g","caption":"EREN"},"url":"https:\/\/www.europeanrealestate.org\/blog\/author\/eren\/"}]}},"_links":{"self":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts\/5603"}],"collection":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/comments?post=5603"}],"version-history":[{"count":5,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts\/5603\/revisions"}],"predecessor-version":[{"id":9335,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts\/5603\/revisions\/9335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/media\/9310"}],"wp:attachment":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/media?parent=5603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/categories?post=5603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/tags?post=5603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}