{"id":6030,"date":"2018-04-12T09:30:59","date_gmt":"2018-04-12T07:30:59","guid":{"rendered":"https:\/\/www.lesmaisonsdeluxe.com\/info\/?p=6030"},"modified":"2019-07-31T11:04:09","modified_gmt":"2019-07-31T09:04:09","slug":"villae-13-luxe-decoration-interieur-technologie","status":"publish","type":"post","link":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/","title":{"rendered":"Villae 13 : luxe, d\u00e9coration d&#8217;int\u00e9rieur et technologie"},"content":{"rendered":"<p>Luxe, d\u00e9coration d&#8217;int\u00e9rieur et technologie sont les trois concepts sur lesquels repose cette nouvelle \u00e9dition de Villae International. Le design d&#8217;int\u00e9rieur devient le leitmotiv de la derni\u00e8re \u00e9dition de Villae International, un magazine publi\u00e9 par EREN avec des contenus exclusifs. En plus, vous pouvez trouver un \u00e9chantillon des <strong>propri\u00e9t\u00e9s les plus luxueuses d&#8217;Europe<\/strong>, tir\u00e9 du portefeuille de chacun des membres du r\u00e9seau immobilier europ\u00e9en.<\/p>\n<p>D\u00e8s la couverture, nous pouvons entrevoir que le design int\u00e9rieur est le v\u00e9ritable protagoniste de Villae 13. Y est illustr\u00e9 un \u00e9l\u00e9gant <strong>loft imp\u00e9rial<\/strong> situ\u00e9 au c\u0153ur de Vienne, qui combine une d\u00e9coration int\u00e9rieure raffin\u00e9e et de somptueux \u00e9l\u00e9ments architecturaux. Ces derniers ont \u00e9t\u00e9 h\u00e9rit\u00e9s du b\u00e2timent historique dans lequel il se trouve.<\/p>\n<h2>Le dernier cri du luxe, d\u00e9coration d&#8217;int\u00e9rieur et technologie<\/h2>\n<p>Un des contenus que vous trouverez dans le magazine sont les nouvelles tendances en mati\u00e8re de d\u00e9coration telles que l&#8217;utilisation de tissus pour donner une touche de glamour et cr\u00e9er un espace cosy. Il y a \u00e9galement une section consacr\u00e9e \u00e0 les luxueux domaines de campagne et les propri\u00e9t\u00e9s les plus exclusives en Europe.<\/p>\n<p>Mais la conception des espaces ne se limite pas seulement au secteur r\u00e9sidentiel, elle s&#8217;\u00e9tend aux avions de luxe et aux bars exclusifs. Des villes comme Mumbai, Xanthi ou Singapour ont cette derni\u00e8re, dont le magazine propose une petite s\u00e9lection.<\/p>\n<p>D&#8217;autres th\u00e8mes exclusifs vous attendent \u00e9galement \u00e0 l&#8217;int\u00e9rieur, parmi lesquels un article sur le visionnaire <strong>Elon Musk<\/strong> \u2013directeur et co-fondateur de Tesla Motors, SolarCity, PayPal, SpaceX et OpenAI,entre autres soci\u00e9t\u00e9s leaders \u2013, le monde de l&#8217;or, les nouveaux gadgets technologiques et les villes intelligentes.<\/p>\n<p>D&#8217;autre part, comme dans chaque \u00e9dition, Villae 13 passe \u00e9galement en revue les conf\u00e9rences annuelles EREN qui ont eu lieu l&#8217;ann\u00e9e derni\u00e8re en Autriche et en France. A cette occasion, EREN a \u00e9galement le plaisir de pr\u00e9senter un nouveau membre, le <strong>Comptoir Immobilier<\/strong>. \u00a0Il s&#8217;agit d&#8217;une agence immobili\u00e8re leader sur le march\u00e9 immobilier \u00e0 Gen\u00e8ve, en Suisse, qui poss\u00e8de \u00e9galement une division de luxe <strong>CI Exclusive Properties<\/strong>.<\/p>\n<p>Vous pouvez, si vous le souhaitez, lire Villae 13 ainsi que les \u00e9ditions pr\u00e9c\u00e9dentes du magazine Villae International \u00e0 travers ce <a href=\"https:\/\/www.europeanrealestate.org\/fr\/villae-international-magazine\/13\">lien<\/a>.<\/p>\n<div id='gallery-1' class='gallery galleryid-6030 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1-1024x685.jpg\" class=\"attachment-large size-large\" alt=\"Luxueux domaines de campagne en Europe\" srcset=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1.jpg 1024w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1-300x201.jpg 300w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-1-768x514.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"523\" src=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2-1024x686.jpg\" class=\"attachment-large size-large\" alt=\"Avions de luxe\" srcset=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2.jpg 1024w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2-300x201.jpg 300w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-2-768x515.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3-1024x685.jpg\" class=\"attachment-large size-large\" alt=\"Bars exclusifs\" srcset=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3.jpg 1024w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3-300x201.jpg 300w, https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-INTERIOR-3-768x514.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, de design int\u00e9rieur et de technologie \u00e0 travers les propri\u00e9t\u00e9s les plus luxueuses d&#8217;Europe.<\/p>\n","protected":false},"author":1,"featured_media":9311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1089],"tags":[5153,5227,5163,5141,5173,5183],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luxe, d\u00e9coration d&#039;int\u00e9rieur et technologie en Villae 13 | EREN<\/title>\n<meta name=\"description\" content=\"Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, d\u00e9coration d&#039;int\u00e9rieur et technologie et les propri\u00e9t\u00e9s les plus luxueuses d&#039;Europe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luxe, d\u00e9coration d&#039;int\u00e9rieur et technologie en Villae 13 | EREN\" \/>\n<meta property=\"og:description\" content=\"Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, d\u00e9coration d&#039;int\u00e9rieur et technologie et les propri\u00e9t\u00e9s les plus luxueuses d&#039;Europe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\" \/>\n<meta property=\"og:site_name\" content=\"EREN\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-12T07:30:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-31T09:04:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EREN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EREN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\"},\"author\":{\"name\":\"EREN\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d\"},\"headline\":\"Villae 13 : luxe, d\u00e9coration d&#8217;int\u00e9rieur et technologie\",\"datePublished\":\"2018-04-12T07:30:59+00:00\",\"dateModified\":\"2019-07-31T09:04:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\"},\"wordCount\":406,\"publisher\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"keywords\":[\"D\u00e9coration d\u2019int\u00e9rieur\",\"EREN\",\"Luxe\",\"Magazine Villae International\",\"Propri\u00e9t\u00e9s de luxe en Europe\",\"Technologie\"],\"articleSection\":[\"Magazine Villae International\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\",\"name\":\"Luxe, d\u00e9coration d'int\u00e9rieur et technologie en Villae 13 | EREN\",\"isPartOf\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"datePublished\":\"2018-04-12T07:30:59+00:00\",\"dateModified\":\"2019-07-31T09:04:09+00:00\",\"description\":\"Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, d\u00e9coration d'int\u00e9rieur et technologie et les propri\u00e9t\u00e9s les plus luxueuses d'Europe.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"contentUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg\",\"width\":1024,\"height\":685,\"caption\":\"Luxe, d\u00e9coration d'int\u00e9rieur et technologie dans le magazine Villae 13\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.europeanrealestate.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villae 13 : luxe, d\u00e9coration d&rsquo;int\u00e9rieur et technologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#website\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/\",\"name\":\"EREN\",\"description\":\"European Real Estate Network\",\"publisher\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.europeanrealestate.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#organization\",\"name\":\"EREN\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg\",\"contentUrl\":\"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg\",\"width\":184,\"height\":14,\"caption\":\"EREN\"},\"image\":{\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d\",\"name\":\"EREN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g\",\"caption\":\"EREN\"},\"url\":\"https:\/\/www.europeanrealestate.org\/blog\/author\/eren\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luxe, d\u00e9coration d'int\u00e9rieur et technologie en Villae 13 | EREN","description":"Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, d\u00e9coration d'int\u00e9rieur et technologie et les propri\u00e9t\u00e9s les plus luxueuses d'Europe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/","og_locale":"es_ES","og_type":"article","og_title":"Luxe, d\u00e9coration d'int\u00e9rieur et technologie en Villae 13 | EREN","og_description":"Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, d\u00e9coration d'int\u00e9rieur et technologie et les propri\u00e9t\u00e9s les plus luxueuses d'Europe.","og_url":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/","og_site_name":"EREN","article_published_time":"2018-04-12T07:30:59+00:00","article_modified_time":"2019-07-31T09:04:09+00:00","og_image":[{"width":1024,"height":685,"url":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","type":"image\/jpeg"}],"author":"EREN","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EREN","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#article","isPartOf":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/"},"author":{"name":"EREN","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d"},"headline":"Villae 13 : luxe, d\u00e9coration d&#8217;int\u00e9rieur et technologie","datePublished":"2018-04-12T07:30:59+00:00","dateModified":"2019-07-31T09:04:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/"},"wordCount":406,"publisher":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#organization"},"image":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","keywords":["D\u00e9coration d\u2019int\u00e9rieur","EREN","Luxe","Magazine Villae International","Propri\u00e9t\u00e9s de luxe en Europe","Technologie"],"articleSection":["Magazine Villae International"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/","url":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/","name":"Luxe, d\u00e9coration d'int\u00e9rieur et technologie en Villae 13 | EREN","isPartOf":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage"},"image":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","datePublished":"2018-04-12T07:30:59+00:00","dateModified":"2019-07-31T09:04:09+00:00","description":"Villae 13 passe en revue les derni\u00e8res tendances en mati\u00e8re de luxe, d\u00e9coration d'int\u00e9rieur et technologie et les propri\u00e9t\u00e9s les plus luxueuses d'Europe.","breadcrumb":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#primaryimage","url":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","contentUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/07\/VILLAE-13-EREN.jpg","width":1024,"height":685,"caption":"Luxe, d\u00e9coration d'int\u00e9rieur et technologie dans le magazine Villae 13"},{"@type":"BreadcrumbList","@id":"https:\/\/www.europeanrealestate.org\/blog\/fr\/villae-13-luxe-decoration-interieur-technologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.europeanrealestate.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Villae 13 : luxe, d\u00e9coration d&rsquo;int\u00e9rieur et technologie"}]},{"@type":"WebSite","@id":"https:\/\/www.europeanrealestate.org\/blog\/#website","url":"https:\/\/www.europeanrealestate.org\/blog\/","name":"EREN","description":"European Real Estate Network","publisher":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.europeanrealestate.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.europeanrealestate.org\/blog\/#organization","name":"EREN","url":"https:\/\/www.europeanrealestate.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg","contentUrl":"https:\/\/www.europeanrealestate.org\/blog\/wp-content\/uploads\/2019\/05\/EREN_LOGO.svg","width":184,"height":14,"caption":"EREN"},"image":{"@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/6a5818c38bd30c858e2236707d38658d","name":"EREN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.europeanrealestate.org\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13d3e33b6bb55067dd20ab7a5d23c488?s=96&d=mm&r=g","caption":"EREN"},"url":"https:\/\/www.europeanrealestate.org\/blog\/author\/eren\/"}]}},"_links":{"self":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts\/6030"}],"collection":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/comments?post=6030"}],"version-history":[{"count":4,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts\/6030\/revisions"}],"predecessor-version":[{"id":9334,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/posts\/6030\/revisions\/9334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/media\/9311"}],"wp:attachment":[{"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/media?parent=6030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/categories?post=6030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europeanrealestate.org\/blog\/wp-json\/wp\/v2\/tags?post=6030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}